{"id":12781,"date":"2025-07-31T10:42:18","date_gmt":"2025-07-31T08:42:18","guid":{"rendered":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/?p=12781"},"modified":"2025-08-01T11:13:09","modified_gmt":"2025-08-01T09:13:09","slug":"chiusura-di-agosto","status":"publish","type":"post","link":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/","title":{"rendered":"Chiusura di agosto"},"content":{"rendered":"<p>Proprio cos\u00ec, ma <strong>torneremo pi\u00f9 cariche che mai dal 25 agosto<\/strong> per altre tre settimane di gite, pizze fatte a mano, avventura, musica e tante risate.<br \/>\n<strong>Non ci siamo dal 2 al 24 agosto<\/strong>.<br \/>\nIl Summercamp torna dal 25 agosto al 12 settembre.<br \/>\nPuoi gi\u00e0 prenotare il Summercamp &#8216;del rientro&#8217;.<\/p>\n<h3>Prenota o richiedi ulteriori informazioni<\/h3>\n<p>Per prenotare\u00a0 <strong>contattaci attraverso il form e-mail<\/strong>.<\/p>\n<div style=\"margin-top: 0px;\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f12351-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"12351\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/posts\/12781#wpcf7-f12351-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"12351\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f12351-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.3\" \/>\n<\/div>\n<div class=\"row contact\" style=\"background-image:none !important; background-color: transparent !important; padding-top:30px!important; padding-left: 20px; padding-right: 20px; margin-top:40px;\" id=\"form\" name=\"form\">\n<!--\nHTML Input Types: https:\/\/www.w3schools.com\/html\/html_form_input_types.asp \nCSS Rounded Corners: https:\/\/www.w3schools.com\/css\/css3_borders.asp\n-->\n\t<style>\n.form-ben-posizionato {margin-left:auto; margin-top:-70px; margin-bottom:0px;}\n@media (max-width: 1151px) {\n .form-ben-posizionato {margin-left:auto; margin-top:-70px;}}\n.form-ben-posizionato input[type=\"text\"], .form-ben-posizionato input[type=\"tel\"], .form-ben-posizionato input[type=\"email\"], .form-ben-posizionato input[type=\"submit\"], textarea {border-radius: 10px !important; margin-bottom: -14px !important;}\n.form-ben-posizionato input {border:1px solid #cccccc; background-color:#F7F9FD !important; color:#444444 !important;}\n.form-ben-posizionato input:focus, .form-ben-posizionato input:hover {background-color:#ffffff !important; border:1px solid #f5f5f5 !important; border:1px solid #0088cc !important;}\ninput.submit-by-mario[type=\"submit\"] { border:0px !important; background-color:#2C52A5 !important; width:100% !important; color:#ffffff !important; font-size: 20px !important; font-weight: normal !important;}\ntextarea { padding-top:14px; border:1px solid #cccccc; background-color:#f8fbfb !important;}\ntextarea:focus, textarea:hover {background-color:#ffffff !important; border:1px solid #f5f5f5 !important; border:1px solid #0088cc !important;}\ninput[type=\"checkbox\"] {\n outline: none;\n padding: 3px 0px 3px 3px;\n margin: 0px 1px 3px 0px;\n border: 1px solid #DDDDDD;\n width:24px;\n height:24px;}\ninput[type=\"checkbox\"]:focus {\n \/* box-shadow: 0 0 5px #0088cc; *\/\n padding: 3px 0px 3px 3px;\n margin: 0px 1px 3px 0px;\n border: 1px solid #0088cc;\n width:25px;\n height:25px;}\ntd {padding: 6px !important;}\n\t<\/style>\n\t<div class=\"hidden\">\n\t<span class=\"wpcf7-form-control-wrap URL\" data-name=\"URL\"><input type=\"hidden\" name=\"URL\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"https:\/\/www.pingusenglish.it\/asili-bilingue\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/posts\/12781\"><\/span>\n\t<span class=\"wpcf7-form-control-wrap TITLE_POST\" data-name=\"TITLE_POST\"><input type=\"hidden\" name=\"TITLE_POST\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Chiusura di agosto\"><\/span>\n\t<span class=\"wpcf7-form-control-wrap NOME_DELLA_SCUOLA\" data-name=\"NOME_DELLA_SCUOLA\"><input type=\"hidden\" name=\"NOME_DELLA_SCUOLA\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"PEIK Bologna Mazzini\"><\/span>\n\t<\/div>\n\t<div class=\"row\">\n\t\t<div class=\"form-ben-posizionato\">\n\t\t\t<p style=\"font-size:13px; margin-top:10px;\"><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome e cognome *\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail *\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><span id=\"wpcf7-6a58186b5ee3c-wrapper\" class=\"wpcf7-form-control-wrap email-wrap\" style=\"display:none !important; visibility:hidden !important;\"><label for=\"wpcf7-6a58186b5ee3c-field\" class=\"hp-message\">Si prega di lasciare vuoto questo campo.<\/label><input id=\"wpcf7-6a58186b5ee3c-field\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"email\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span>\n\t\t\t<\/p>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-child-age\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Et\u00e0 bimbo\/a *\" value=\"\" type=\"text\" name=\"your-child-age\" \/><\/span>\n\t\t\t<\/p>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"Telefono \/ cellulare\" value=\"\" type=\"tel\" name=\"your-phone\" \/><\/span>\n\t\t\t<\/p>\n\t\t\t<table style=\"margin-top:22px; margin-left:-20px; max-height:10px !important; background-color: transparent !important; border: 0px #000000 solid !important;\">\n\t\t\t\t<tr style=\"background-color: transparent !important;\">\n\t\t\t\t\t<td style=\"width:32px; line-height:0px;\">\n\t\t\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-privacy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-privacy\" value=\"1\" class=\"contact-privacy\" aria-invalid=\"false\" \/><\/span><\/span><\/span>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/td>\n\t\t\t\t\t<td style=\"margin-left:0px; padding-left:10px; line-height:14px; vertical-align: middle !important;\">\n\t\t\t\t\t\t<p><label for=\"contact-privacy\" style=\"color:#444444; font-size:12px;\">Ho letto le <a style=\"text-decoration:underline;\" href=\"https:\/\/www.pingusenglish.it\/gdpr.html\" target=\"_blank\">Politiche di Privacy<\/a> *<\/label>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\t\t\t\t<tr style=\"background-color: transparent !important;\">\n\t\t\t\t\t<td style=\"width:32px; line-height:0px;\">\n\t\t\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-news\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-news\" value=\"1\" class=\"contact-news\" aria-invalid=\"false\" \/><\/span><\/span><\/span>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/td>\n\t\t\t\t\t<td style=\"margin-left:0px; padding-left:10px; line-height:14px; vertical-align: middle !important;\">\n\t\t\t\t\t\t<p><label for=\"contact-news\" style=\"color:#444444; font-size:12px; padding-top:0px !important; padding-bottom:0px !important;\">Desidero ricevere offerte personalizzate e le vostre news<\/label>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\t\t\t<\/table>\n\t\t\t<div class=\"button-holder\" style=\"margin-top:-10px !important; margin-left:0px;\">\n\t\t\t\t<p class=\"purple-button\" style=\"\"><input class=\"wpcf7-form-control wpcf7-submit has-spinner submit-by-mario\" type=\"submit\" value=\"RICHIEDI INFORMAZIONI\" \/>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Proprio cos\u00ec, ma torneremo pi\u00f9 cariche che mai dal 25 agosto per altre tre settimane di gite, pizze fatte a mano, avventura, musica e tante risate. Non ci siamo dal<\/p>\n","protected":false},"author":1,"featured_media":12782,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-12781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chiusura di agosto<\/title>\n<meta name=\"description\" content=\"Proprio cos\u00ec, ma torniamo pi\u00f9 cariche che mai dal 25 agosto, per altre tre settimane di gite, pizze fatte a mano, avventura, musica e tante risate.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiusura di agosto\" \/>\n<meta property=\"og:description\" content=\"Proprio cos\u00ec, ma torniamo pi\u00f9 cariche che mai dal 25 agosto, per altre tre settimane di gite, pizze fatte a mano, avventura, musica e tante risate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/\" \/>\n<meta property=\"og:site_name\" content=\"Bologna Mazzini - Pingu&#039;s English International Kindergarten\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-31T08:42:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-01T09:13:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/ferie-estive-2025.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmaster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmaster\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/\",\"url\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/\",\"name\":\"Chiusura di agosto\",\"isPartOf\":{\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/ferie-estive-2025.webp\",\"datePublished\":\"2025-07-31T08:42:18+00:00\",\"dateModified\":\"2025-08-01T09:13:09+00:00\",\"author\":{\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#\/schema\/person\/ebdee0ecad43d70ce0a41dc3b57d8d4f\"},\"description\":\"Proprio cos\u00ec, ma torniamo pi\u00f9 cariche che mai dal 25 agosto, per altre tre settimane di gite, pizze fatte a mano, avventura, musica e tante risate.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/#primaryimage\",\"url\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/ferie-estive-2025.webp\",\"contentUrl\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/ferie-estive-2025.webp\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chiusura di agosto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#website\",\"url\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/\",\"name\":\"Bologna Mazzini - Pingu&#039;s English International Kindergarten\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#\/schema\/person\/ebdee0ecad43d70ce0a41dc3b57d8d4f\",\"name\":\"webmaster\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/40c47d506be9192fc3f980f27a6f7df6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/40c47d506be9192fc3f980f27a6f7df6?s=96&d=mm&r=g\",\"caption\":\"webmaster\"},\"sameAs\":[\"https:\/\/www.pingusenglish.it\/asili-bilingue\"],\"url\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/author\/webmaster\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiusura di agosto","description":"Proprio cos\u00ec, ma torniamo pi\u00f9 cariche che mai dal 25 agosto, per altre tre settimane di gite, pizze fatte a mano, avventura, musica e tante risate.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/","og_locale":"it_IT","og_type":"article","og_title":"Chiusura di agosto","og_description":"Proprio cos\u00ec, ma torniamo pi\u00f9 cariche che mai dal 25 agosto, per altre tre settimane di gite, pizze fatte a mano, avventura, musica e tante risate.","og_url":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/","og_site_name":"Bologna Mazzini - Pingu&#039;s English International Kindergarten","article_published_time":"2025-07-31T08:42:18+00:00","article_modified_time":"2025-08-01T09:13:09+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/ferie-estive-2025.webp","type":"image\/jpeg"}],"author":"webmaster","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"webmaster","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/","url":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/","name":"Chiusura di agosto","isPartOf":{"@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/#primaryimage"},"image":{"@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/ferie-estive-2025.webp","datePublished":"2025-07-31T08:42:18+00:00","dateModified":"2025-08-01T09:13:09+00:00","author":{"@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#\/schema\/person\/ebdee0ecad43d70ce0a41dc3b57d8d4f"},"description":"Proprio cos\u00ec, ma torniamo pi\u00f9 cariche che mai dal 25 agosto, per altre tre settimane di gite, pizze fatte a mano, avventura, musica e tante risate.","breadcrumb":{"@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/#primaryimage","url":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/ferie-estive-2025.webp","contentUrl":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/ferie-estive-2025.webp","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/chiusura-di-agosto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/"},{"@type":"ListItem","position":2,"name":"Chiusura di agosto"}]},{"@type":"WebSite","@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#website","url":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/","name":"Bologna Mazzini - Pingu&#039;s English International Kindergarten","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#\/schema\/person\/ebdee0ecad43d70ce0a41dc3b57d8d4f","name":"webmaster","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/40c47d506be9192fc3f980f27a6f7df6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/40c47d506be9192fc3f980f27a6f7df6?s=96&d=mm&r=g","caption":"webmaster"},"sameAs":["https:\/\/www.pingusenglish.it\/asili-bilingue"],"url":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/author\/webmaster\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/posts\/12781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/comments?post=12781"}],"version-history":[{"count":1,"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/posts\/12781\/revisions"}],"predecessor-version":[{"id":12786,"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/posts\/12781\/revisions\/12786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/media\/12782"}],"wp:attachment":[{"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/media?parent=12781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/categories?post=12781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/tags?post=12781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}