{"id":12794,"date":"2025-08-14T12:45:10","date_gmt":"2025-08-14T10:45:10","guid":{"rendered":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/?p=12794"},"modified":"2025-12-27T12:33:39","modified_gmt":"2025-12-27T11:33:39","slug":"novita-di-settembre","status":"publish","type":"post","link":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/","title":{"rendered":"Ti accompagniamo fino alle superiori: le novit\u00e0 di settembre che vi sorprenderanno"},"content":{"rendered":"<p>BIG NEWS! Da settembre Pingu&#8217;s English Bologna Mazzini vi accompagna <strong>fino alle superiori<\/strong>.<br \/>\nCome genitori attenti, sapete quanto sia cruciale dare ai vostri figli gli strumenti giusti per vivere il futuro. Tra questi c\u2019\u00e8 l&#8217;apprendimento dell&#8217;inglese in un percorso che <strong>cresce con loro<\/strong>, che li prepara al mondo di domani. Un livello di inglese che sia certificato, quindi riconosciuto.<\/p>\n<h3>Dalla scuola materna alle superiori con Pingu\u2019s English!<\/h3>\n<p>Fino ad oggi abbiamo accompagnato i vostri figli fino ai 12 anni; in questi anni abbiamo ricevuto moltissime richieste per arrivare alla fine della scuola media. Vi abbiamo ascoltato!<br \/>\nEbbene s\u00ec, con la partenza dei corsi di settembre 2025, <strong>anche gli adolescenti di 14 anni troveranno un corso efficace e coinvolgente, adeguato alle loro esigenze<\/strong>.<\/p>\n<p>Vostro figlio di 3 anni, che oggi muove i primi passi nell\u2019apprendimento dell\u2019inglese, potr\u00e0 continuare il suo viaggio fino alla soglia delle superiori con Pingu\u2019s English, in un <strong>percorso fluido e senza interruzioni<\/strong>, che lo porter\u00e0 al <strong>bilinguismo<\/strong>, se vorr\u00e0.<br \/>\n<strong>Questo \u00e8 fondamentale<\/strong> perch\u00e9 gli studi ci dicono che ogni interruzione nel percorso di apprendimento pu\u00f2 comportare una perdita del 30-40% delle competenze acquisite. Noi questo vogliamo evitarlo.<\/p>\n<h3>Certificazione Cambridge B1 &#8211; PET: la seconda novit\u00e0.<\/h3>\n<p>Ma c&#8217;\u00e8 di pi\u00f9. Quest&#8217;anno introduciamo qualcosa di speciale: la <strong>certificazione Cambridge B1 Preliminary per la scuola<\/strong>, la prova tangibile che vostro figlio ha le <strong>competenze avanzate<\/strong> della lingua e proseguir\u00e0 con le certificazioni internazionali Cambridge, sostenendo gli esami presso la nostra scuola.<\/p>\n<p>Lui si  mette alla prova e conferma la sua preparazione e la sua capacit\u00e0 di affrontare nuove sfide. Questo \u00e8 un risultato che gli d\u00e0 grande soddisfazione.<\/p>\n<h3>Il momento \u00e8 adesso: prenota una lezione gratuita!<\/h3>\n<p>Le iscrizioni per settembre sono aperte, ma i posti sono limitati. Non perch\u00e9 vogliamo creare false urgenze, ma perch\u00e9 crediamo davvero nell&#8217;importanza di gruppi piccoli e omogenei. <strong>Ogni bambino merita attenzione<\/strong>.<\/p>\n<p><strong>Ti accompagniamo fino alle superiori. Questa non \u00e8 una promessa, \u00e8 il nostro impegno!<\/strong><br \/>\nContattaci subito: <strong>ti regaliamo una lezione di prova<\/strong>: \u201ctoccherai con mano\u201d quello che hai letto fino a qui.<br \/>\nPer prenotare\u00a0compila il form e-mail presente su questa pagina. Un componente dello staff ti chiamer\u00e0 in tempi brevi.<\/p>\n<div style=\"margin-top: 0px;\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f12351-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"12351\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/posts\/12794#wpcf7-f12351-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"12351\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f12351-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.3\" \/>\n<\/div>\n<div class=\"row contact\" style=\"background-image:none !important; background-color: transparent !important; padding-top:30px!important; padding-left: 20px; padding-right: 20px; margin-top:40px;\" id=\"form\" name=\"form\">\n<!--\nHTML Input Types: https:\/\/www.w3schools.com\/html\/html_form_input_types.asp \nCSS Rounded Corners: https:\/\/www.w3schools.com\/css\/css3_borders.asp\n-->\n\t<style>\n.form-ben-posizionato {margin-left:auto; margin-top:-70px; margin-bottom:0px;}\n@media (max-width: 1151px) {\n .form-ben-posizionato {margin-left:auto; margin-top:-70px;}}\n.form-ben-posizionato input[type=\"text\"], .form-ben-posizionato input[type=\"tel\"], .form-ben-posizionato input[type=\"email\"], .form-ben-posizionato input[type=\"submit\"], textarea {border-radius: 10px !important; margin-bottom: -14px !important;}\n.form-ben-posizionato input {border:1px solid #cccccc; background-color:#F7F9FD !important; color:#444444 !important;}\n.form-ben-posizionato input:focus, .form-ben-posizionato input:hover {background-color:#ffffff !important; border:1px solid #f5f5f5 !important; border:1px solid #0088cc !important;}\ninput.submit-by-mario[type=\"submit\"] { border:0px !important; background-color:#2C52A5 !important; width:100% !important; color:#ffffff !important; font-size: 20px !important; font-weight: normal !important;}\ntextarea { padding-top:14px; border:1px solid #cccccc; background-color:#f8fbfb !important;}\ntextarea:focus, textarea:hover {background-color:#ffffff !important; border:1px solid #f5f5f5 !important; border:1px solid #0088cc !important;}\ninput[type=\"checkbox\"] {\n outline: none;\n padding: 3px 0px 3px 3px;\n margin: 0px 1px 3px 0px;\n border: 1px solid #DDDDDD;\n width:24px;\n height:24px;}\ninput[type=\"checkbox\"]:focus {\n \/* box-shadow: 0 0 5px #0088cc; *\/\n padding: 3px 0px 3px 3px;\n margin: 0px 1px 3px 0px;\n border: 1px solid #0088cc;\n width:25px;\n height:25px;}\ntd {padding: 6px !important;}\n\t<\/style>\n\t<div class=\"hidden\">\n\t<span class=\"wpcf7-form-control-wrap URL\" data-name=\"URL\"><input type=\"hidden\" name=\"URL\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"https:\/\/www.pingusenglish.it\/asili-bilingue\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/posts\/12794\"><\/span>\n\t<span class=\"wpcf7-form-control-wrap TITLE_POST\" data-name=\"TITLE_POST\"><input type=\"hidden\" name=\"TITLE_POST\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Ti accompagniamo fino alle superiori: le novit\u00e0 di settembre che vi sorprenderanno\"><\/span>\n\t<span class=\"wpcf7-form-control-wrap NOME_DELLA_SCUOLA\" data-name=\"NOME_DELLA_SCUOLA\"><input type=\"hidden\" name=\"NOME_DELLA_SCUOLA\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"PEIK Bologna Mazzini\"><\/span>\n\t<\/div>\n\t<div class=\"row\">\n\t\t<div class=\"form-ben-posizionato\">\n\t\t\t<p style=\"font-size:13px; margin-top:10px;\"><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome e cognome *\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail *\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><span id=\"wpcf7-6a580a6f59a33-wrapper\" class=\"wpcf7-form-control-wrap email-wrap\" style=\"display:none !important; visibility:hidden !important;\"><label for=\"wpcf7-6a580a6f59a33-field\" class=\"hp-message\">Si prega di lasciare vuoto questo campo.<\/label><input id=\"wpcf7-6a580a6f59a33-field\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"email\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span>\n\t\t\t<\/p>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-child-age\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Et\u00e0 bimbo\/a *\" value=\"\" type=\"text\" name=\"your-child-age\" \/><\/span>\n\t\t\t<\/p>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"Telefono \/ cellulare\" value=\"\" type=\"tel\" name=\"your-phone\" \/><\/span>\n\t\t\t<\/p>\n\t\t\t<table style=\"margin-top:22px; margin-left:-20px; max-height:10px !important; background-color: transparent !important; border: 0px #000000 solid !important;\">\n\t\t\t\t<tr style=\"background-color: transparent !important;\">\n\t\t\t\t\t<td style=\"width:32px; line-height:0px;\">\n\t\t\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-privacy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-privacy\" value=\"1\" class=\"contact-privacy\" aria-invalid=\"false\" \/><\/span><\/span><\/span>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/td>\n\t\t\t\t\t<td style=\"margin-left:0px; padding-left:10px; line-height:14px; vertical-align: middle !important;\">\n\t\t\t\t\t\t<p><label for=\"contact-privacy\" style=\"color:#444444; font-size:12px;\">Ho letto le <a style=\"text-decoration:underline;\" href=\"https:\/\/www.pingusenglish.it\/gdpr.html\" target=\"_blank\">Politiche di Privacy<\/a> *<\/label>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\t\t\t\t<tr style=\"background-color: transparent !important;\">\n\t\t\t\t\t<td style=\"width:32px; line-height:0px;\">\n\t\t\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-news\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"your-news\" value=\"1\" class=\"contact-news\" aria-invalid=\"false\" \/><\/span><\/span><\/span>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/td>\n\t\t\t\t\t<td style=\"margin-left:0px; padding-left:10px; line-height:14px; vertical-align: middle !important;\">\n\t\t\t\t\t\t<p><label for=\"contact-news\" style=\"color:#444444; font-size:12px; padding-top:0px !important; padding-bottom:0px !important;\">Desidero ricevere offerte personalizzate e le vostre news<\/label>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/td>\n\t\t\t\t<\/tr>\n\t\t\t<\/table>\n\t\t\t<div class=\"button-holder\" style=\"margin-top:-10px !important; margin-left:0px;\">\n\t\t\t\t<p class=\"purple-button\" style=\"\"><input class=\"wpcf7-form-control wpcf7-submit has-spinner submit-by-mario\" type=\"submit\" value=\"RICHIEDI INFORMAZIONI\" \/>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>BIG NEWS! Da settembre Pingu&#8217;s English Bologna Mazzini vi accompagna <strong>fino alle superiori<\/strong>. Come genitori attenti, sapete quanto sia cruciale dare ai vostri figli gli strumenti giusti per vivere il futuro.<\/p>\n","protected":false},"author":1,"featured_media":12797,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-12794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le novit\u00e0 di settembre che vi sorprenderanno<\/title>\n<meta name=\"description\" content=\"Pingu&#039;s English Bologna Mazzini vi accompagna fino alle superiori. Sapete quanto siano cruciali gli strumenti giusti per vivere il futuro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le novit\u00e0 di settembre che vi sorprenderanno\" \/>\n<meta property=\"og:description\" content=\"Pingu&#039;s English Bologna Mazzini vi accompagna fino alle superiori. Sapete quanto siano cruciali gli strumenti giusti per vivere il futuro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Bologna Mazzini - Pingu&#039;s English International Kindergarten\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-14T10:45:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-27T11:33:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/settembre-2025_1200x630px-png.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"webmaster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmaster\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/\",\"url\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/\",\"name\":\"Le novit\u00e0 di settembre che vi sorprenderanno\",\"isPartOf\":{\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/settembre-2025_1200x630px-png.webp\",\"datePublished\":\"2025-08-14T10:45:10+00:00\",\"dateModified\":\"2025-12-27T11:33:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#\/schema\/person\/ebdee0ecad43d70ce0a41dc3b57d8d4f\"},\"description\":\"Pingu's English Bologna Mazzini vi accompagna fino alle superiori. Sapete quanto siano cruciali gli strumenti giusti per vivere il futuro.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/#primaryimage\",\"url\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/settembre-2025_1200x630px-png.webp\",\"contentUrl\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/settembre-2025_1200x630px-png.webp\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ti accompagniamo fino alle superiori: le novit\u00e0 di settembre che vi sorprenderanno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#website\",\"url\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/\",\"name\":\"Bologna Mazzini - Pingu&#039;s English International Kindergarten\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#\/schema\/person\/ebdee0ecad43d70ce0a41dc3b57d8d4f\",\"name\":\"webmaster\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/40c47d506be9192fc3f980f27a6f7df6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/40c47d506be9192fc3f980f27a6f7df6?s=96&d=mm&r=g\",\"caption\":\"webmaster\"},\"sameAs\":[\"https:\/\/www.pingusenglish.it\/asili-bilingue\"],\"url\":\"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/author\/webmaster\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le novit\u00e0 di settembre che vi sorprenderanno","description":"Pingu's English Bologna Mazzini vi accompagna fino alle superiori. Sapete quanto siano cruciali gli strumenti giusti per vivere il futuro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/","og_locale":"it_IT","og_type":"article","og_title":"Le novit\u00e0 di settembre che vi sorprenderanno","og_description":"Pingu's English Bologna Mazzini vi accompagna fino alle superiori. Sapete quanto siano cruciali gli strumenti giusti per vivere il futuro.","og_url":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/","og_site_name":"Bologna Mazzini - Pingu&#039;s English International Kindergarten","article_published_time":"2025-08-14T10:45:10+00:00","article_modified_time":"2025-12-27T11:33:39+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/settembre-2025_1200x630px-png.webp","type":"image\/png"}],"author":"webmaster","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"webmaster","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/","url":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/","name":"Le novit\u00e0 di settembre che vi sorprenderanno","isPartOf":{"@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/#primaryimage"},"image":{"@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/settembre-2025_1200x630px-png.webp","datePublished":"2025-08-14T10:45:10+00:00","dateModified":"2025-12-27T11:33:39+00:00","author":{"@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#\/schema\/person\/ebdee0ecad43d70ce0a41dc3b57d8d4f"},"description":"Pingu's English Bologna Mazzini vi accompagna fino alle superiori. Sapete quanto siano cruciali gli strumenti giusti per vivere il futuro.","breadcrumb":{"@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/#primaryimage","url":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/settembre-2025_1200x630px-png.webp","contentUrl":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-content\/uploads\/sites\/15\/2025\/08\/settembre-2025_1200x630px-png.webp","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/2025\/novita-di-settembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/"},{"@type":"ListItem","position":2,"name":"Ti accompagniamo fino alle superiori: le novit\u00e0 di settembre che vi sorprenderanno"}]},{"@type":"WebSite","@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#website","url":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/","name":"Bologna Mazzini - Pingu&#039;s English International Kindergarten","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#\/schema\/person\/ebdee0ecad43d70ce0a41dc3b57d8d4f","name":"webmaster","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/40c47d506be9192fc3f980f27a6f7df6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/40c47d506be9192fc3f980f27a6f7df6?s=96&d=mm&r=g","caption":"webmaster"},"sameAs":["https:\/\/www.pingusenglish.it\/asili-bilingue"],"url":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/author\/webmaster\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/posts\/12794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/comments?post=12794"}],"version-history":[{"count":1,"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/posts\/12794\/revisions"}],"predecessor-version":[{"id":12817,"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/posts\/12794\/revisions\/12817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/media\/12797"}],"wp:attachment":[{"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/media?parent=12794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/categories?post=12794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pingusenglish.it\/asili-bilingue\/bologna-mazzini\/wp-json\/wp\/v2\/tags?post=12794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}